{"id":5502,"date":"2020-11-23T09:19:58","date_gmt":"2020-11-23T14:19:58","guid":{"rendered":"http:\/\/localhost\/crea_site\/?post_type=cortos&amp;p=5502"},"modified":"2020-11-23T09:19:58","modified_gmt":"2020-11-23T14:19:58","slug":"24-de-marzo-quarantine","status":"publish","type":"post","link":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/","title":{"rendered":"24 de Marzo Quarantine"},"content":{"rendered":"\n<p>A partir de las medidas de aislamiento obligatorio decretadas en Colombia y Per\u00fa, 24 de Marzo Quarantine, narra aquellas incertidumbres, miedos y an\u00e9cdotas a trav\u00e9s de una polifon\u00eda  de personajes, que reflejan diversas formas de afrontar un confinamiento, con sus diferentes pensares y sentires alrededor de lo que significa que el mundo y su mundo paren por un momento. Este cortometraje es una pieza terminada que hace parte de la narrativa introductoria y de presentaci\u00f3n de personajes, del web documental \u00ab24 de Marzo Quarantine\u00bb; proyecto que busca hacer conciencia sobre los efectos psicol\u00f3gicos de un confinamiento y proponer formas de superarlos. Ver p\u00e1gina en construcci\u00f3n en: https:\/\/bigfishcrea.wixsite.com\/24demarzoquarantine<\/p>\n    \t    \t ","protected":false},"excerpt":{"rendered":"<p>A partir de las medidas de aislamiento obligatorio decretadas en Colombia y Per\u00fa, 24 de Marzo Quarantine, narra aquellas incertidumbres, miedos y an\u00e9cdotas a trav\u00e9s de una polifon\u00eda de personajes, que reflejan diversas formas de afrontar un confinamiento, con sus diferentes pensares y sentires alrededor de lo que significa que el mundo y su mundo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>24 de Marzo Quarantine - Festival de Cortos 2020<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 de Marzo Quarantine - Festival de Cortos 2020\" \/>\n<meta property=\"og:description\" content=\"A partir de las medidas de aislamiento obligatorio decretadas en Colombia y Per\u00fa, 24 de Marzo Quarantine, narra aquellas incertidumbres, miedos y an\u00e9cdotas a trav\u00e9s de una polifon\u00eda de personajes, que reflejan diversas formas de afrontar un confinamiento, con sus diferentes pensares y sentires alrededor de lo que significa que el mundo y su mundo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/\" \/>\n<meta property=\"og:site_name\" content=\"Festival de Cortos 2020\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-23T14:19:58+00:00\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/\",\"url\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/\",\"name\":\"24 de Marzo Quarantine - Festival de Cortos 2020\",\"isPartOf\":{\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#website\"},\"datePublished\":\"2020-11-23T14:19:58+00:00\",\"dateModified\":\"2020-11-23T14:19:58+00:00\",\"author\":{\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/5071c2e3cdaee5612c3ba0e2c9dc40e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 de Marzo Quarantine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#website\",\"url\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/\",\"name\":\"Festival de Cortos 2020\",\"description\":\"Explora Crea Micrositios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/5071c2e3cdaee5612c3ba0e2c9dc40e8\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/73fa2de0474c53f6496b25afa67e469d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/73fa2de0474c53f6496b25afa67e469d?s=96&d=mm&r=g\",\"caption\":\"webmaster\"},\"url\":\"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/author\/webmaster\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 de Marzo Quarantine - Festival de Cortos 2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/","og_locale":"es_ES","og_type":"article","og_title":"24 de Marzo Quarantine - Festival de Cortos 2020","og_description":"A partir de las medidas de aislamiento obligatorio decretadas en Colombia y Per\u00fa, 24 de Marzo Quarantine, narra aquellas incertidumbres, miedos y an\u00e9cdotas a trav\u00e9s de una polifon\u00eda de personajes, que reflejan diversas formas de afrontar un confinamiento, con sus diferentes pensares y sentires alrededor de lo que significa que el mundo y su mundo [&hellip;]","og_url":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/","og_site_name":"Festival de Cortos 2020","article_published_time":"2020-11-23T14:19:58+00:00","author":"webmaster","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webmaster","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/","url":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/","name":"24 de Marzo Quarantine - Festival de Cortos 2020","isPartOf":{"@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#website"},"datePublished":"2020-11-23T14:19:58+00:00","dateModified":"2020-11-23T14:19:58+00:00","author":{"@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/5071c2e3cdaee5612c3ba0e2c9dc40e8"},"breadcrumb":{"@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/24-de-marzo-quarantine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/"},{"@type":"ListItem","position":2,"name":"24 de Marzo Quarantine"}]},{"@type":"WebSite","@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#website","url":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/","name":"Festival de Cortos 2020","description":"Explora Crea Micrositios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/5071c2e3cdaee5612c3ba0e2c9dc40e8","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/73fa2de0474c53f6496b25afa67e469d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73fa2de0474c53f6496b25afa67e469d?s=96&d=mm&r=g","caption":"webmaster"},"url":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/posts\/5502"}],"collection":[{"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/comments?post=5502"}],"version-history":[{"count":0,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/posts\/5502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/media?parent=5502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/categories?post=5502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.crea.gov.co\/festival-de-cortos-2020\/wp-json\/wp\/v2\/tags?post=5502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}